{"id":59153,"date":"2018-04-07T04:26:27","date_gmt":"2018-04-06T20:26:27","guid":{"rendered":"http:\/\/forgemind.net\/media\/512a489af9\/"},"modified":"2023-02-13T14:37:25","modified_gmt":"2023-02-13T06:37:25","slug":"%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85","status":"publish","type":"post","link":"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/","title":{"rendered":"\u5f69\u8272\u58d3\u82b1\u5730\u576a\uff0c\u65bd\u5de5\u6642\u5fc5\u9808\u6ce8\u610f\u4e8b\u9805"},"content":{"rendered":"<p>\u4ecb\u7d39\u58d3\u82b1\u5730\u576a\u65bd\u5de5\u6642\u9700\u8981\u6ce8\u610f\u7684\u554f\u984c\uff0c\u5305\u62ec\u74b0\u5883\u548c\u65bd\u5de5\u8981\u9ede\u3002<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/forgemind.net\/media\/wp-content\/uploads\/2021\/04\/41617769594.jpg\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u5167\u5bb9\u76ee\u9304<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04acbb4a196\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04acbb4a196\"  aria-label=\"\u986f\u793a\/\u96b1\u85cf\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#1%E3%80%81%E6%BA%96%E5%82%99%E5%B7%A5%E4%BD%9C\" >1\u3001\u6e96\u5099\u5de5\u4f5c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#2%E3%80%81%E8%80%83%E6%85%AE%E6%96%BD%E4%BD%9C%E9%9D%A2%E5%BC%B7%E5%BA%A6\" >2\u3001\u8003\u616e\u65bd\u4f5c\u9762\u5f37\u5ea6<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#3%E3%80%81%E8%A1%A8%E5%B1%A4%E5%B9%B3%E6%95%B4%E5%BA%A6\" >3\u3001\u8868\u5c64\u5e73\u6574\u5ea6<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#4%E3%80%81%E5%BC%B7%E5%8C%96%E6%96%99%E5%8F%AF%E8%83%BD%E6%9C%83%E7%B5%90%E5%A1%8A\" >4\u3001\u5f37\u5316\u6599\u53ef\u80fd\u6703\u7d50\u584a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#5%E3%80%81%E4%B8%8D%E5%8F%AF%E7%81%91%E6%B0%B4\" >5\u3001\u4e0d\u53ef\u7051\u6c34<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#6%E3%80%81%E5%A3%93%E8%8A%B1%E6%99%82%E6%A9%9F\" >6\u3001\u58d3\u82b1\u6642\u6a5f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#7%E3%80%81%E6%A8%A1%E5%85%B7%E6%BA%96%E5%82%99\" >7\u3001\u6a21\u5177\u6e96\u5099<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#8%E3%80%81%E7%8F%BE%E5%A0%B4%E4%BF%9D%E8%AD%B7\" >8\u3001\u73fe\u5834\u4fdd\u8b77<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#9%E3%80%81%E5%A3%93%E8%8A%B1%E5%BE%8C%E6%B8%85%E6%BD%94\" >9\u3001\u58d3\u82b1\u5f8c\u6e05\u6f54<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#10%E3%80%81%E6%B3%A8%E6%84%8F%E6%B0%A3%E5%80%99\" >10\u3001\u6ce8\u610f\u6c23\u5019<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/forgemind.net\/media\/%e5%bd%a9%e8%89%b2%e5%a3%93%e8%8a%b1%e5%9c%b0%e5%9d%aa%ef%bc%8c%e6%96%bd%e5%b7%a5%e6%99%82%e5%bf%85%e9%a0%88%e6%b3%a8%e6%84%8f%e4%ba%8b%e9%a0%85\/#11%E3%80%81%E6%96%BD%E5%B7%A5%E7%AE%A1%E7%90%86\" >11\u3001\u65bd\u5de5\u7ba1\u7406<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"1%E3%80%81%E6%BA%96%E5%82%99%E5%B7%A5%E4%BD%9C\"><\/span>1\u3001\u6e96\u5099\u5de5\u4f5c<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u6e96\u5099\u5de5\u4f5c\u8981\u505a\u597d\u3002\u65bd\u5de5\u6642\u61c9\u5c07\u5f85\u92ea\u7bc9\u7684\u5f69\u8272\u58d3\u82b1\u5730\u576a\u5f37\u5316\u6599\u3001\u812b\u6a21\u7c89\u6309\u92ea\u7bc9\u65b9\u5411\u4f9d\u5e8f\u5806\u653e\u53ca\u4f7f\u7528\uff0c\u5404\u7a2e\u5c08\u696d\u65bd\u5de5\u5de5\u5177\u53ca\u6210\u578b\u6a21\u5177\u7b49\u4e5f\u61c9\u8655\u65bc\u826f\u597d\u7684\u5de5\u4f5c\u72c0\u614b\u3002<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2%E3%80%81%E8%80%83%E6%85%AE%E6%96%BD%E4%BD%9C%E9%9D%A2%E5%BC%B7%E5%BA%A6\"><\/span>2\u3001\u8003\u616e\u65bd\u4f5c\u9762\u5f37\u5ea6<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u8981\u6839\u64da\u5c0d\u6df7\u51dd\u571f\u5730\u9762\u5f37\u5ea6\u60c5\u6cc1\u9032\u884c\u5404\u985e\u6e96\u5099\u5de5\u4f5c\u3002<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/forgemind.net\/media\/wp-content\/uploads\/2021\/04\/101617769597.jpg\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"3%E3%80%81%E8%A1%A8%E5%B1%A4%E5%B9%B3%E6%95%B4%E5%BA%A6\"><\/span>3\u3001\u8868\u5c64\u5e73\u6574\u5ea6<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u6df7\u51dd\u571f\u9762\u5c64\u7684\u8655\u7406\u5fc5\u9808\u6309\u7167\u898f\u5b9a\u53ca\u8a2d\u8a08\u8981\u6c42\u9032\u884c\uff0c\u8868\u5c64\u4e00\u5b9a\u8981\u9054\u5230\u6240\u8981\u6c42\u7684\u5e73\u6574\u5ea6\u3002\u6df7\u51dd\u571f\u7684\u54c1\u8cea\u4e5f\u8981\u4fdd\u6301\u4e00\u81f4\uff0c\u9019\u5c0d\u6700\u7d42\u6574\u9ad4\u6548\u679c\u975e\u5e38\u91cd\u8981\u3002<\/p>\n<h3><span class=\"ez-toc-section\" id=\"4%E3%80%81%E5%BC%B7%E5%8C%96%E6%96%99%E5%8F%AF%E8%83%BD%E6%9C%83%E7%B5%90%E5%A1%8A\"><\/span>4\u3001\u5f37\u5316\u6599\u53ef\u80fd\u6703\u7d50\u584a<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u5f69\u8272\u58d3\u82b1\u5730\u576a\u5f37\u5316\u6599\u5728\u904b\u8f38\u9014\u4e2d\u53ef\u80fd\u6703\u7d50\u584a\uff0c\u5fc5\u9808\u7528\u96d9\u624b\u6253\u6563\u5f37\u5316\u6599\u518d\u4f7f\u7528\u3002<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/forgemind.net\/media\/wp-content\/uploads\/2021\/04\/41617769601.jpg\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"5%E3%80%81%E4%B8%8D%E5%8F%AF%E7%81%91%E6%B0%B4\"><\/span>5\u3001\u4e0d\u53ef\u7051\u6c34<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u4e0d\u80fd\u5728\u64ad\u6492\u4e86\u5f37\u5316\u5291\u7684\u6df7\u51dd\u571f\u7684\u9762\u5c64\u4e0a\u7051\u6c34\uff0c\u9019\u6a23\u6703\u5c0e\u81f4\u984f\u8272\u7684\u4e0d\u4e00\u81f4\u3002<\/p>\n<h3><span class=\"ez-toc-section\" id=\"6%E3%80%81%E5%A3%93%E8%8A%B1%E6%99%82%E6%A9%9F\"><\/span>6\u3001\u58d3\u82b1\u6642\u6a5f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u638c\u63e1\u58d3\u82b1\u7684\u6642\u9593\u975e\u5e38\u91cd\u8981\uff0c\u592a\u6fd5\u6216\u592a\u4e7e\u7684\u6df7\u51dd\u571f\u8868\u9762\u90fd\u6703\u5f71\u97ff\u6700\u5f8c\u7684\u5716\u6848\u53ca\u6548\u679c\u3002<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/forgemind.net\/media\/wp-content\/uploads\/2021\/04\/61617769606.jpg\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"7%E3%80%81%E6%A8%A1%E5%85%B7%E6%BA%96%E5%82%99\"><\/span>7\u3001\u6a21\u5177\u6e96\u5099<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u6210\u578b\u6a21\u548c\u908a\u89d2\u6a21\u53ef\u4ee5\u91cd\u8907\u4f7f\u7528\uff0c\u4f46\u5fc5\u9808\u5099\u6709\u8db3\u5920\u6578\u91cf\u7684\u6a21\u5177\uff0c\u4ee5\u63d0\u9ad8\u65bd\u5de5\u6548\u7387\u3002<\/p>\n<h3><span class=\"ez-toc-section\" id=\"8%E3%80%81%E7%8F%BE%E5%A0%B4%E4%BF%9D%E8%AD%B7\"><\/span>8\u3001\u73fe\u5834\u4fdd\u8b77<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u65bd\u5de5\u5f8c\u7684\u5f69\u8272\u58d3\u82b1\u5730\u576a\u4e0d\u9700\u8981\u7051\u6c34\u9032\u884c\u990a\u8b77\uff0c\u4f46\u5728\u9a57\u6536\u524d\u5fc5\u9808\u505a\u597d\u5fc5\u8981\u7684\u73fe\u5834\u4fdd\u8b77\u5de5\u4f5c\u3002<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/forgemind.net\/media\/wp-content\/uploads\/2021\/04\/81617769610.jpg\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"9%E3%80%81%E5%A3%93%E8%8A%B1%E5%BE%8C%E6%B8%85%E6%BD%94\"><\/span>9\u3001\u58d3\u82b1\u5f8c\u6e05\u6f54<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u58d3\u597d\u7684\u5f69\u8272\u58d3\u82b1\u7d0b\u8def\u5716\u6848\u4e7e\u71e5\u4e4b\u5f8c\uff0c\u901a\u5e38\u662f\u5728\u65bd\u5de5\u58d3\u82b1\u5f8c\u7684\u7b2c\u4e8c\u5929\uff0c\u4f7f\u7528\u9ad8\u58d3\u6c96\u6d17\u6a5f\u6d17\u638980%\u5de6\u53f3\u6df7\u51dd\u571f\u8868\u5c64\u7684\u812b\u6a21\u7c89\u3002<\/p>\n<h3><span class=\"ez-toc-section\" id=\"10%E3%80%81%E6%B3%A8%E6%84%8F%E6%B0%A3%E5%80%99\"><\/span>10\u3001\u6ce8\u610f\u6c23\u5019<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u65bd\u5de5\u6642\u7684\u6c23\u5019\u5c0d\u65bd\u5de5\u54c1\u8cea\u6709\u5f88\u5927\u7a0b\u5ea6\u7684\u5f71\u97ff\uff0c\u5f69\u8272\u58d3\u82b1\u5730\u576a\u7684\u65bd\u5de5\u61c9\u8ff4\u907f\u96e8\u3001\u96ea\u3001\u98a8\u6c99\u53ca\u51b0\u51cd\u7684\u5929\u6c23\uff0c\u65e5\u591c\u6eab\u5dee\u5927\u7684\u5730\u65b9\uff0c\u665a\u4e0a\u4e5f\u61c9\u7981\u6b62\u65bd\u5de5\u3002<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/forgemind.net\/media\/wp-content\/uploads\/2021\/04\/81617769613.jpg\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"11%E3%80%81%E6%96%BD%E5%B7%A5%E7%AE%A1%E7%90%86\"><\/span>11\u3001\u65bd\u5de5\u7ba1\u7406<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u826f\u597d\u7684\u65bd\u5de5\u74b0\u5883\u624d\u80fd\u78ba\u4fdd\u65bd\u5de5\u7684\u54c1\u8cea\uff0c\u5f69\u8272\u58d3\u82b1\u5730\u576a\u65bd\u5de5\u6642\u61c9\u76e1\u91cf\u907f\u514d\u540c\u5176\u5b83\u7684\u5de5\u73ed\u4ea4\u53c9\u65bd\u5de5\uff0c\u5fc5\u8981\u6642\u61c9\u5c0d\u65bd\u5de5\u73fe\u5834\u63a1\u53d6\u5c01\u9589\u63aa\u65bd\u3002<\/p>\n<p>\u4ee5\u4e0a\u5c31\u662f\u5f69\u8272\u58d3\u82b1\u5730\u576a\u65bd\u5de5\u6642\u9700\u8981\u6ce8\u610f\u7684\u5730\u65b9\uff0c\u552f\u6709\u9019\u4e9b\u7d30\u90e8\u505a\u597d\uff0c\u624d\u80fd\u78ba\u4fdd\u6700\u5f8c\u7684\u5730\u576a\u54c1\u8cea\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u672c\u6587\u4ecb\u7d39\u58d3\u82b1\u5730\u576a\u65bd\u5de5\u6642\u9700\u8981\u6ce8\u610f\u7684\u554f\u984c\uff0c\u5305\u62ec\u74b0\u5883\u548c\u65bd\u5de5\u8981\u9ede\u3002<\/p>\n","protected":false},"author":1,"featured_media":59154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,25],"tags":[9944],"class_list":{"0":"post-59153","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-architecture-practice","8":"category-construction","9":"tag-9944"},"_links":{"self":[{"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/posts\/59153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/comments?post=59153"}],"version-history":[{"count":0,"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/posts\/59153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/media\/59154"}],"wp:attachment":[{"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/media?parent=59153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/categories?post=59153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forgemind.net\/media\/wp-json\/wp\/v2\/tags?post=59153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}